{"id":13453,"date":"2025-01-06T14:14:11","date_gmt":"2025-01-06T19:14:11","guid":{"rendered":"https:\/\/galvatech2000.com\/?post_type=realisations&#038;p=13453"},"modified":"2025-01-06T14:36:36","modified_gmt":"2025-01-06T19:36:36","slug":"j-napoleon-perusse-footbridge-amqui","status":"publish","type":"realisations","link":"https:\/\/galvatech2000.com\/en\/realisations\/j-napoleon-perusse-footbridge-amqui\/","title":{"rendered":"J-Napol\u00e9on P\u00e9russe footbridge \/ Amqui"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"13453\" class=\"elementor elementor-13453\" data-elementor-post-type=\"realisations\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f8bd6c5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f8bd6c5\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-36850b9\" data-id=\"36850b9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-98c2dae elementor-widget elementor-widget-text-editor\" data-id=\"98c2dae\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Construction of a new footbridge in 2022.<\/p><p>Steel galavanized with Rust-Anode Primer by Atelier de Soudure Gilles Roy of Amqui.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-92ea4e9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"92ea4e9\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e2c58ad\" data-id=\"e2c58ad\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3662357 elementor-widget elementor-widget-image\" data-id=\"3662357\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/galvatech2000.com\/wp-content\/uploads\/IMG_9033-768x1024.jpeg\" class=\"attachment-large size-large wp-image-13442\" alt=\"\" srcset=\"https:\/\/galvatech2000.com\/wp-content\/uploads\/IMG_9033-768x1024.jpeg 768w, https:\/\/galvatech2000.com\/wp-content\/uploads\/IMG_9033-600x800.jpeg 600w, https:\/\/galvatech2000.com\/wp-content\/uploads\/IMG_9033-225x300.jpeg 225w, https:\/\/galvatech2000.com\/wp-content\/uploads\/IMG_9033-1152x1536.jpeg 1152w, https:\/\/galvatech2000.com\/wp-content\/uploads\/IMG_9033.jpeg 1536w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e48c09b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e48c09b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b26e25e\" data-id=\"b26e25e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7831000 elementor-widget elementor-widget-image\" data-id=\"7831000\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"479\" height=\"1024\" src=\"https:\/\/galvatech2000.com\/wp-content\/uploads\/Pont-Amqui.5-479x1024.jpg\" class=\"attachment-large size-large wp-image-13427\" alt=\"\" srcset=\"https:\/\/galvatech2000.com\/wp-content\/uploads\/Pont-Amqui.5-479x1024.jpg 479w, https:\/\/galvatech2000.com\/wp-content\/uploads\/Pont-Amqui.5-600x1281.jpg 600w, https:\/\/galvatech2000.com\/wp-content\/uploads\/Pont-Amqui.5-140x300.jpg 140w, https:\/\/galvatech2000.com\/wp-content\/uploads\/Pont-Amqui.5-768x1640.jpg 768w, https:\/\/galvatech2000.com\/wp-content\/uploads\/Pont-Amqui.5-719x1536.jpg 719w, https:\/\/galvatech2000.com\/wp-content\/uploads\/Pont-Amqui.5.jpg 944w\" sizes=\"(max-width: 479px) 100vw, 479px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e611458 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e611458\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-bc3b782\" data-id=\"bc3b782\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f0473d2 elementor-widget elementor-widget-image\" data-id=\"f0473d2\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/galvatech2000.com\/wp-content\/uploads\/Pont-Amqui.1-1024x768.jpg\" class=\"attachment-large size-large wp-image-13421\" alt=\"\" srcset=\"https:\/\/galvatech2000.com\/wp-content\/uploads\/Pont-Amqui.1-1024x768.jpg 1024w, https:\/\/galvatech2000.com\/wp-content\/uploads\/Pont-Amqui.1-600x450.jpg 600w, https:\/\/galvatech2000.com\/wp-content\/uploads\/Pont-Amqui.1-300x225.jpg 300w, https:\/\/galvatech2000.com\/wp-content\/uploads\/Pont-Amqui.1-768x576.jpg 768w, https:\/\/galvatech2000.com\/wp-content\/uploads\/Pont-Amqui.1-1536x1152.jpg 1536w, https:\/\/galvatech2000.com\/wp-content\/uploads\/Pont-Amqui.1.jpg 2016w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-104c39a\" data-id=\"104c39a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a78e8d3 elementor-widget elementor-widget-image\" data-id=\"a78e8d3\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/galvatech2000.com\/wp-content\/uploads\/vers-la-captive-1024x768.jpg\" class=\"attachment-large size-large wp-image-13445\" alt=\"\" srcset=\"https:\/\/galvatech2000.com\/wp-content\/uploads\/vers-la-captive-1024x768.jpg 1024w, https:\/\/galvatech2000.com\/wp-content\/uploads\/vers-la-captive-600x450.jpg 600w, https:\/\/galvatech2000.com\/wp-content\/uploads\/vers-la-captive-300x225.jpg 300w, https:\/\/galvatech2000.com\/wp-content\/uploads\/vers-la-captive-768x576.jpg 768w, https:\/\/galvatech2000.com\/wp-content\/uploads\/vers-la-captive.jpg 1360w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Construction of a new footbridge in 2022. Steel galavanized with Rust-Anode Primer by Atelier de Soudure Gilles Roy of Amqui.<\/p>\n","protected":false},"author":8,"featured_media":13440,"template":"","meta":{"_acf_changed":false},"categories-realisations":[94,97,99],"class_list":["post-13453","realisations","type-realisations","status-publish","has-post-thumbnail","hentry","categories-realisations-maritime-area","categories-realisations-structures-area","categories-realisations-transport-area"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/galvatech2000.com\/en\/wp-json\/wp\/v2\/realisations\/13453","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/galvatech2000.com\/en\/wp-json\/wp\/v2\/realisations"}],"about":[{"href":"https:\/\/galvatech2000.com\/en\/wp-json\/wp\/v2\/types\/realisations"}],"author":[{"embeddable":true,"href":"https:\/\/galvatech2000.com\/en\/wp-json\/wp\/v2\/users\/8"}],"version-history":[{"count":6,"href":"https:\/\/galvatech2000.com\/en\/wp-json\/wp\/v2\/realisations\/13453\/revisions"}],"predecessor-version":[{"id":13463,"href":"https:\/\/galvatech2000.com\/en\/wp-json\/wp\/v2\/realisations\/13453\/revisions\/13463"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/galvatech2000.com\/en\/wp-json\/wp\/v2\/media\/13440"}],"wp:attachment":[{"href":"https:\/\/galvatech2000.com\/en\/wp-json\/wp\/v2\/media?parent=13453"}],"wp:term":[{"taxonomy":"categories-realisations","embeddable":true,"href":"https:\/\/galvatech2000.com\/en\/wp-json\/wp\/v2\/categories-realisations?post=13453"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}